{"id":3,"date":"2022-02-07T15:17:41","date_gmt":"2022-02-07T14:17:41","guid":{"rendered":"http:\/\/aef-elkantara.fr\/?page_id=3"},"modified":"2022-03-02T17:45:14","modified_gmt":"2022-03-02T16:45:14","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Qui sommes-nous&nbsp;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019adresse de notre site est&nbsp;: http:\/\/aef-elkantara.fr.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Commentaires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici&nbsp;: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9dias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab&nbsp;Se souvenir de moi&nbsp;\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Utilisation et transmission de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\"> <\/strong>Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l\u2019e-mail de r\u00e9initialisation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dur\u00e9es de stockage de vos donn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\"> <\/strong>Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les droits que vous avez sur vos donn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Transmission de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui sommes-nous&nbsp;? L\u2019adresse de notre site est&nbsp;: http:\/\/aef-elkantara.fr. Commentaires Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables. Une cha\u00eene anonymis\u00e9e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - AEF el Kantara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - AEF el Kantara\" \/>\n<meta property=\"og:description\" content=\"Qui sommes-nous&nbsp;? L\u2019adresse de notre site est&nbsp;: http:\/\/aef-elkantara.fr. Commentaires Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables. Une cha\u00eene anonymis\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"AEF el Kantara\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T16:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/les-gorges.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - AEF el Kantara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aef-elkantara.fr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/les-gorges.jpg\",\"datePublished\":\"2022-02-07T14:17:41+00:00\",\"dateModified\":\"2022-03-02T16:45:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aef-elkantara.fr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/les-gorges.jpg\",\"contentUrl\":\"https:\\\/\\\/aef-elkantara.fr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/les-gorges.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aef-elkantara.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#website\",\"url\":\"https:\\\/\\\/aef-elkantara.fr\\\/\",\"name\":\"AEF el Kantara\",\"description\":\"Assoc d\u2019El Kantara vivant en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aef-elkantara.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#organization\",\"name\":\"AEF el Kantara\",\"url\":\"https:\\\/\\\/aef-elkantara.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aef-elkantara.fr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Black-logo-no-background.png\",\"contentUrl\":\"https:\\\/\\\/aef-elkantara.fr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Black-logo-no-background.png\",\"width\":3183,\"height\":3113,\"caption\":\"AEF el Kantara\"},\"image\":{\"@id\":\"https:\\\/\\\/aef-elkantara.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - AEF el Kantara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - AEF el Kantara","og_description":"Qui sommes-nous&nbsp;? L\u2019adresse de notre site est&nbsp;: http:\/\/aef-elkantara.fr. Commentaires Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, mais aussi votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables. Une cha\u00eene anonymis\u00e9e [&hellip;]","og_url":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/","og_site_name":"AEF el Kantara","article_modified_time":"2022-03-02T16:45:14+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/les-gorges.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/","url":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - AEF el Kantara","isPartOf":{"@id":"https:\/\/aef-elkantara.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/#primaryimage"},"image":{"@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/#primaryimage"},"thumbnailUrl":"https:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/les-gorges.jpg","datePublished":"2022-02-07T14:17:41+00:00","dateModified":"2022-03-02T16:45:14+00:00","breadcrumb":{"@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/#primaryimage","url":"https:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/les-gorges.jpg","contentUrl":"https:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/les-gorges.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/aef-elkantara.fr\/index.php\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aef-elkantara.fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/aef-elkantara.fr\/#website","url":"https:\/\/aef-elkantara.fr\/","name":"AEF el Kantara","description":"Assoc d\u2019El Kantara vivant en France","publisher":{"@id":"https:\/\/aef-elkantara.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aef-elkantara.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aef-elkantara.fr\/#organization","name":"AEF el Kantara","url":"https:\/\/aef-elkantara.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aef-elkantara.fr\/#\/schema\/logo\/image\/","url":"https:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/Black-logo-no-background.png","contentUrl":"https:\/\/aef-elkantara.fr\/wp-content\/uploads\/2022\/02\/Black-logo-no-background.png","width":3183,"height":3113,"caption":"AEF el Kantara"},"image":{"@id":"https:\/\/aef-elkantara.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":2,"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":412,"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/media\/14"}],"wp:attachment":[{"href":"https:\/\/aef-elkantara.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}